{"id":5397,"date":"2021-02-12T13:40:12","date_gmt":"2021-02-12T13:40:12","guid":{"rendered":"https:\/\/germanmarcano.com\/germansite\/?page_id=5397"},"modified":"2021-02-12T14:33:37","modified_gmt":"2021-02-12T14:33:37","slug":"don-quijote","status":"publish","type":"page","link":"https:\/\/germanmarcano.com\/germansite\/en\/don-quijote\/","title":{"rendered":"Don Quixote op. Richard Strauss Op. 35: A reception history  by German Marcano"},"content":{"rendered":"<section data-kc-fullwidth=\"content\" class=\"kc-elm kc-css-150948 kc_row\"><div class=\"kc-row-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-580584 kc_col-sm-12 kc_column kc_col-sm-12\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-573823 kc_text_block\"><\/p>\n<p style=\"text-align: center;\"><strong>DON QUIJOTE OP. 35<\/strong><\/p>\n<p style=\"text-align: center;\">Poema Sinf\u00f3nico<\/p>\n<p style=\"text-align: center;\">Richard Strauss<\/p>\n<p style=\"text-align: center;\"><strong>Historia de un Recibimiento<\/strong><\/p>\n<p style=\"text-align: center;\">por Germ\u00e1n Marcano<\/p>\n<\/p>\n<p style=\"text-align: center;\"><em>&#8220;La ejecuci\u00f3n \u00a0del Poema Sonoro de Strauss el viernes<\/em><\/p>\n<p style=\"text-align: center;\"><em>en la tarde y anoche por la Orquesta Sinf\u00f3nica de Chicago<\/em><\/p>\n<p style=\"text-align: center;\"><em>debi\u00f3 haber despertado una buena cantidad de discusiones entre<\/em><\/p>\n<p style=\"text-align: center;\"><em>los m\u00fasicos. Es bastante f\u00e1cil desacreditar ciertas tendencias<\/em><\/p>\n<p style=\"text-align: center;\"><em>como fuera de la esfera de la verdadera m\u00fasica; pero cuando uno<\/em><\/p>\n<p style=\"text-align: center;\"><em>es confrontado con un trabajo que atrae tan directamente <\/em><\/p>\n<p style=\"text-align: center;\"><em>la imaginaci\u00f3n como el &#8220;Don Quijote\" del que ser\u00eda tonto <\/em><\/p>\n<p style=\"text-align: center;\"><em>negar sus m\u00e9ritos art\u00edsticos, \u00bfqu\u00e9 pasar\u00e1 con la teor\u00eda? El<\/em><\/p>\n<p style=\"text-align: center;\"><em>&#8220;Don Quijote es ciertamente una obra de arte, \u00bfpero a qu\u00e9 secci\u00f3n<\/em><\/p>\n<p style=\"text-align: center;\"><em>del arte pertenece, si no es a la m\u00fasica?<\/em><\/p>\n<p style=\"text-align: center;\"><em>\u2026Pero, un poema sonoro como el \u201cDon Quijote\u201d de Richard Strauss<\/em><\/p>\n<p style=\"text-align: center;\"><em>ser\u00eda condenado \u2026porque indudablemente contiene<\/em><\/p>\n<p style=\"text-align: center;\"><em>pasajes que son distintivamente feos como m\u00fasica, pero<\/em><\/p>\n<p style=\"text-align: center;\"><em>tienen su valor como imitaciones.\"<\/em><\/p>\n<p style=\"text-align: center; padding-left: 80px;\">La Tribuna de Chicago, 8 de enero de 1899<\/p>\n<p style=\"text-align: center;\"><em>&#8220;Es dif\u00edcil garantizar los postulados del compositor, y se necesitar\u00e1 mucho <\/em><\/p>\n<p style=\"text-align: center;\"><em>reajuste de ideas antes que el &#8220;Don Quijote\", <\/em><\/p>\n<p style=\"text-align: center;\"><em>con todas sus bellezas, no pueda escucharse de ninguna otra manera <\/em><\/p>\n<p style=\"text-align: center;\"><em>sino como una haza\u00f1a. Ni tampoco dejar\u00e1 de darse la pregunta <\/em><\/p>\n<p style=\"text-align: center;\"><em>acerca de cu\u00e1n lejos el compositor quiere ser tomado seriamente en ello; <\/em><\/p>\n<p style=\"text-align: center;\"><em>cu\u00e1n lejos se concentra en llevar a cabo la mistificaci\u00f3n sugerida en su pedante t\u00edtulo con su convencional<\/em><\/p>\n<p style=\"text-align: center;\"><em>descripci\u00f3n italiana: cu\u00e1n lejos quiere presionar \u00e9l lo &#8220;Fant\u00e1stico\"<\/em><\/p>\n<p style=\"text-align: center;\"><em>de lo que en ella advierte.\"<\/em><\/p>\n<p style=\"padding-left: 80px; text-align: center;\">El Times de Nueva York, 19 de febrero de 1904.<\/p>\n<p>Inspirado en la famosa novela espa\u00f1ola de 1605 de Miguel de Cervantes Saavedra (1547-1616), el Poema Sinf\u00f3nico <em>Don Quijote<\/em> Op. 35 es la sexta de una serie de diez obras maestras program\u00e1ticas escritas por Richard Strauss (1864-1949) entre 1886 y 1915. Compuesto en 1897 y por primera vez ejecutado en 1898, Don Quijote destaca como su ejemplo m\u00e1s fino de pintura musical, y, como el director Norman Del Mar sostiene &#8220;.\u2026un firme hito en la m\u00fasica orquestal de la Escuela Post-rom\u00e1ntica\"<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Sin embargo, esta obra no ha logrado llegar tan f\u00e1cilmente a las salas de concierto como otros poemas sinf\u00f3nicos del mismo compositor. Mientras composiciones como <em>Don Juan<\/em>, <em>Also Spracht Zarathustra<\/em> (As\u00ed habl\u00f3 Zaratustra) y <em>Ein Heldenleben<\/em> (Vida de H\u00e9roe) siempre han gozado de popularidad entre los oyentes y m\u00fasicos, <em>Don Quijote<\/em> ha por alguna raz\u00f3n generado cr\u00edticas desde que fue compuesta. Muchas de las razones para esta injustificable actitud pueden asociarse con la impracticabilidad de su ejecuci\u00f3n, repudio general a ciertos efectos y, en general, a una falta de conocimiento acerca de lo que el trabajo realmente es.<\/p>\n<p>No hay nada nuevo en presentar las aventuras del ingenuo hidalgo en m\u00fasica.\u00a0 Compositores como Telemann, Purcell, Rubinstein y Massenet han escrito suites y \u00f3peras sobre el tema. Estos primeros esfuerzos, sin embargo, no influenciaron la aproximaci\u00f3n de Strauss en contar las aventuras del famoso caballero y su escudero (\u00e9l apenas los conoc\u00eda) ya que usando la transformaci\u00f3n tem\u00e1tica dispuso de un m\u00e9todo de representaci\u00f3n musical. El trabajo es presentado en tres secciones: una introducci\u00f3n que describe la gradual deterioraci\u00f3n de la salud mental de Don Quijote, un grupo de diez variaciones que corresponden a diez episodios en la novela, y el Ep\u00edlogo, que describe el retorno de Don Quijote a la lucidez y su eventual muerte.<\/p>\n<p>El nombre <em>Variaciones Fant\u00e1sticas sobre un Tema de Car\u00e1cter Caballeresco<\/em>, como lo titul\u00f3 el autor, de alg\u00fan modo es inconducente ya que asocia la composici\u00f3n con la t\u00e9cnica de la variaci\u00f3n cl\u00e1sica y no con la transformaci\u00f3n tem\u00e1tica. Incluso las actuales ejecuciones de <em>Don Quijote<\/em> plantean preguntas entre los escuchas quienes salen de los conciertos habiendo disfrutado el Ep\u00edlogo pero se preguntan en qu\u00e9 consiste el resto de la obra. La reacci\u00f3n general en su primera presentaci\u00f3n<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> fue similar:<\/p>\n<p style=\"text-align: center;\"><em>&#8220;La obra \u2026 suscit\u00f3 el mayor inter\u00e9s \u00a0en todos los\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0m\u00fasicos, sin ganarse siempre &#8211; a la vez -, sus simpat\u00edas\".\u00a0 <\/em><\/p>\n<p style=\"text-align: center; padding-left: 80px;\">Musikalishes Wochenblatt (Semanario Musical Edici\u00f3n No. 12, 1898)<\/p>\n<p>El 18 de marzo, diez d\u00edas despu\u00e9s de su estreno, Strauss dirigi\u00f3 el trabajo en Frankfurt con resultados similares:<\/p>\n<p style=\"text-align: center;\"><em>\" \u2026 el nuevo poema sinf\u00f3nico de R. Strauss, Don Quijote,\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 despert\u00f3 el mayor inter\u00e9s en Frankfurt\u2026y fue<\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 calurosamente aplaudido, aunque haya habido alg\u00fan\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0disentimiento\".<\/em><\/p>\n<p style=\"text-align: center; padding-left: 80px;\">Musikalishes Wochenblatt (Semanario Musical Edici\u00f3n No.13, 1898)<\/p>\n<p>Si el atrevido plan de trabajo de la obra provoca reacciones en su contra, los diferentes efectos que Strauss us\u00f3 para representar algunas de las aventuras del h\u00e9roe, han sido pol\u00e9micos desde su composici\u00f3n hasta el presente. Uno de los episodios del trabajo m\u00e1s comentados es la Variaci\u00f3n II,\u00a0 la cual describe onomatop\u00e9yicamente el balido de las ovejas que Don Quijote atac\u00f3 tom\u00e1ndolas por el poderoso ej\u00e9rcito de Alifanfaron y Pentapolin, Rey del Garamantas (compases 234-40). En estos compases la obra, b\u00e1sicamente tonalmente orientada, toma un giro hacia un estilo completamente atonal y casi aleatorio que se bien era \u00f3ptimo para describir los eventos de la historia, no pod\u00eda ser aceptado por la audiencia de 1898, generando fuertes protestas. La cr\u00edtica de la primera presentaci\u00f3n norteamericana en 1899<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>, se refiere bastante rudamente sobre este pasaje en particular:<\/p>\n<p style=\"text-align: center;\"><em>\" \u2026en honor a la verdad, uno se inclina a sentir un poco de l\u00e1stima que\u00a0 \u00a0\u00a0<\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Richard Strauss no omiti\u00f3 aqu\u00e9llos toques groseramente realistas\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0en &#8220;Don Quijote\" que ciertamente debieron estropear el trabajo para <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 muchos oyentes \u2026por qu\u00e9 no incorporar una oveja de verdad en la <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 orquesta y entrenarla a balar a un momento dado?.\"\u00a0 <\/em><\/p>\n<p style=\"text-align: center; padding-left: 80px;\">La Tribuna de Chicago, 8 de enero de 1899<\/p>\n<p>Cuando la obra se ejecut\u00f3 en Par\u00eds en 1900 dirigida por Strauss, su amigo Romain Rolland record\u00f3 que los franceses tambi\u00e9n reaccionaron fuertemente contra el episodio<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a>:<\/p>\n<p style=\"text-align: center;\"><em>\" \u2026Indignaci\u00f3n en una parte del p\u00fablico. El viejo buen<\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 p\u00fablico franc\u00e9s no tolera un chiste; piensa que se r\u00eden de \u00e9l,\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 el p\u00fablico es irrespetuoso. El balido de la oveja le enfurece.\"\u00a0 <\/em><\/p>\n<p style=\"text-align: center; padding-left: 80px;\">El Diario, 11 de marzo\u00a0 de 1900.<\/p>\n<p>Durante muchos a\u00f1os este pasaje ha sido el centro de discusi\u00f3n entre cr\u00edticos e historiadores cuyos argumentos yerran en entender la naturaleza program\u00e1tica del trabajo e ignoran otras maravillosas descripciones en \u00e9l, como la gradual desintegraci\u00f3n mental del Quijote y su sublime sumisi\u00f3n a la muerte. Es, sin embargo, interesante que donde <em>L&#8217;apres midi d&#8217;un faune<\/em> de Debussy (1897) es considerada la composici\u00f3n pionera de la m\u00fasica del siglo XX, el balido de la oveja de Strauss en <em>Don Quijote<\/em>, m\u00e1s avanzado que cualquier cosa compuesta en ese momento, apenas se menciona en los tratados hist\u00f3ricos.<\/p>\n<p>M\u00e1s que directores y p\u00fablico, han sido los violonchelistas solistas los que principalmente han contribuido al establecimiento del <em>Don Quijote<\/em> de Strauss como una de las m\u00e1s grandes partituras orquestales del siglo XIX. El papel de Don Quijote, asignado por Strauss a un solo de violonchelo, ha sido interpretado por todos los grandes solistas del chelo del siglo XX; algunos de ellos han sido tan identificados con el caballero, que se les lleg\u00f3 a apoderar como \u00e9l. Esto ha cambiado la concepci\u00f3n original de la obra la cual se transform\u00f3 de un Poema Sinf\u00f3nico en un Concierto de Violonchelo.<\/p>\n<p>Ojeando la partitura, uno puede suponer que Strauss quiso darle la parte solista al l\u00edder de la secci\u00f3n de violonchelos de la orquesta con cuidadosas indicaciones dadas al solista. Las ejecuciones modernas de la obra, sin embargo, tienden a adoptar el usual montaje de concierto, d\u00f3nde el solista se sienta delante de la orquesta omiti\u00e9ndose el variado y complejo &#8220;tutti\" de las secciones. Aunque esta presentaci\u00f3n proporciona a la obra un elemento solista visualmente atractivo, la intenci\u00f3n original es una vez m\u00e1s malinterpretada. La presentaci\u00f3n como concierto con solista sentando, se interpone a la elaborada instrumentaci\u00f3n del grupo de violonchelos, y espec\u00edficamente en el acompa\u00f1amiento del solo de la viola, instrumento que hace el papel de Sancho Panza<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a>. A pesar de esto, la obra ya ha adquirido esta tradici\u00f3n de presentaci\u00f3n de concierto, e incluso, fue aceptada por el compositor mismo en a\u00f1os posteriores.<\/p>\n<p>Esta concepci\u00f3n del trabajo como concierto de chelo, crea lo poco pr\u00e1ctico de tener que conseguir un solista para interpretar el papel de <em>Don Quijote<\/em>; alg\u00fan buen reconocido interprete que realce la poca popularidad de la pieza. En vista del problema, la mayor\u00eda de las orquestas prefiere programar conciertos m\u00e1s populares para que as\u00ed la conocida funci\u00f3n doble de composici\u00f3n m\u00e1s un buen solista, pueda cumplirse.<\/p>\n<p>Aparte de la mencionada impracticabilidad, el <em>Don Quijote<\/em> de Strauss requiere de algunas raras exigencia en su orquestaci\u00f3n: una tuba tenor, dos cornos adicionales y, por primera vez en la m\u00fasica Orquestal Occidental, una M\u00e1quina de Producir Viento. Este aparato es incorporado en la VII Variaci\u00f3n (compases 515-25) agregado a r\u00e1pidas escalas crom\u00e1ticas en los vientos para ilustrar el vuelo de Don Quijote y Sancho Panza<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a>. Aunque el uso de este dispositivo tiene una funci\u00f3n program\u00e1tica espec\u00edfica en la obra (tambi\u00e9n la tiene en la Sinfon\u00eda Alpina de 1915), este pensamiento pionero tuvo alguna repercusi\u00f3n en el trabajo de compositores posteriores como Ravel (<em>Dafnis y Cloe<\/em>, 1912), Schoenberg (<em>Jacobleister<\/em>, 1922), Milhaud y Vaughan Williams.<\/p>\n<p>Esta v\u00edvida y exuberante orquestaci\u00f3n del Don Quijote fue quiz\u00e1s el aspecto que m\u00e1s atrajo la atenci\u00f3n de la m\u00e1s vieja generaci\u00f3n de compositores de finales del siglo XIX. Sus habilidades como brillante orquestador fueron reconocidas por compositores y cr\u00edticos famosos de la \u00e9poca de <em>Don Juan<\/em> (1888), aunque muchos de ellos no simpatizasen con sus ideas musicales:<\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0&#8220;El color lo es todo; los pensamientos musicales nada\".\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \" \u2026un virtuoso de la orquesta carente de ideas musicales\" <a href=\"#_ftn7\" name=\"_ftnref7\"><strong>[7]<\/strong><\/a>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><\/p>\n<p style=\"text-align: center; padding-left: 80px;\">Edward Hanslick, 1892<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a><\/p>\n<p>La atrevida orquestaci\u00f3n de Strauss en <em>Don Quijote<\/em> fue, sin embargo, altamente criticada \u00a0por algunos de sus contempor\u00e1neos m\u00e1s viejos:<\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8220;Yo vi la partitura del Don Quijote. \u00a1Cu\u00e1n desvergonzado es \u00a0<\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 este Richard Strauss!\"\u00a0 <\/em><\/p>\n<p style=\"text-align: center; padding-left: 80px;\">Rimski Korsakov<a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a><\/p>\n<p>Otros, al contrario, aplaudieron su inventiva y la llamaron &#8220;Pensamiento Orquestal\"<a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a>:<\/p>\n<p style=\"text-align: center;\"><em>&#8220;\u00bfUna M\u00e1quina de viento? \u00bfPor qu\u00e9 no? Lo \u00fanico que\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 cuenta es si el compositor\u2026alcanza el resultado deseado\" <\/em><\/p>\n<p style=\"text-align: center; padding-left: 40px;\">Antonin Dvorak<a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a><\/p>\n<p>Para 1904, <em>Don Quijote<\/em> hab\u00eda sido ejecutado en la mayor\u00eda de las capitales musicales importantes de Europa y los EEUU. Durante este muy revolucionario tiempo de la historia de la m\u00fasica, la obra llam\u00f3 la atenci\u00f3n de compositores contempor\u00e1neos con ideas m\u00e1s frescas que pod\u00edan tolerar y entender los atrevidos pensamientos de este pol\u00e9mico compositor. El compositor alem\u00e1n Max Reger (1873-1916) qued\u00f3 fascinado de su\u00a0 inventiva al estudiar la partitura en 1902:<\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0&#8220;Recientemente estudi\u00e9 muy \u00e1vidamente el Don Quijote de Richard<\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Strauss; es maravilloso lo que el hombre escribe. Estoy simplemente \u00a0<\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 muy contento y entusiasmado que lo tengamos\"\u00a0 <\/em><\/p>\n<p style=\"text-align: center; padding-left: 80px;\">Correspondencia a Arturo Seidl, Dic 29, 1902.<a href=\"#_ftn12\" name=\"_ftnref12\">[12]<\/a><\/p>\n<p>Otro compositor favorablemente impresionado con el Quijote de Strauss fue Ferrucio Busoni (1866-1924), qui\u00e9n oy\u00f3 el trabajo en dos ocasiones: su segunda presentaci\u00f3n en Nueva York en 1904 (con Strauss dirigiendo), y una ejecuci\u00f3n en Boston posteriormente en 1911. Seg\u00fan Busoni, la ejecuci\u00f3n de la obra en Nueva York, con Casals en el violonchelo, no fue muy exitosa: mala atenci\u00f3n y pobremente interpretada, hubo que comenzar la pieza dos veces. Despu\u00e9s de la actuaci\u00f3n de Boston, sin embargo, su admiraci\u00f3n por el maestro fue expresada en una carta a su esposa:<\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0&#8220;Es un trabajo de gran calidad; ordinario en los\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0momentos l\u00edricos, extraordinariamente excitante en las\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0partes grotescas\u2026, una de las cosas m\u00e1s interesantes\u00a0 <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0y creativas de nuestro tiempo y puede ser lo mejor <\/em><\/p>\n<p style=\"text-align: center;\"><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0de este compositor\"<a href=\"#_ftn13\" name=\"_ftnref13\"><strong>[13]<\/strong><\/a>\u00a0\u00a0 <\/em><\/p>\n<p>A pesar de la gran impresi\u00f3n que el Quijote de Strauss dej\u00f3 en estos contempor\u00e1neos m\u00e1s j\u00f3venes y en otras importantes personalidades, esta obra no puede realmente ser considerada de gran influencia en la m\u00fasica que ven\u00eda. Strauss fue el \u00faltimo de los compositores rom\u00e1ntico del siglo XIX, viviendo en una \u00e9poca en la que los elementos y est\u00e9ticas de composici\u00f3n musical estaban cambiando radicalmente. Ya que el desmoronamiento de la tonalidad era inminente, la m\u00fasica de Strauss experiment\u00f3 m\u00e1s all\u00e1 de la tonalidad sin abandonar el estilo melodioso de sus predecesores alemanes Rom\u00e1nticos. El Poema Sinf\u00f3nico, en su punto m\u00e1s alto para el tiempo del <em>Don Juan<\/em>, perdi\u00f3 la batalla con los cr\u00edticos de la &#8220;M\u00fasica Absoluta\" desapareciendo pr\u00e1cticamente despu\u00e9s de 1915, dejando a Strauss como el \u00faltimo Maestro del g\u00e9nero. Los diez Poemas Sonoros de Richard Strauss representan la culminaci\u00f3n art\u00edstica de un g\u00e9nero que s\u00f3lo existi\u00f3 para tener una relativa peque\u00f1a influencia en la m\u00fasica del siglo XX.<\/p>\n<p>Aunque hoy las audiencias (e incluso los m\u00fasicos) todav\u00eda reaccionen al <em>Don Quijote<\/em> de la misma manera que el p\u00fablico de 1898, la obra tiene un lugar definido en el repertorio de cada gran orquesta, director y violonchelista. Es indiscutiblemente el m\u00e1s fino ejemplo de pintura musical del compositor, su trabajo m\u00e1s atrevido en dise\u00f1o y el m\u00e1s pol\u00e9mico en efectos. Es, de hecho, debido a esta osad\u00eda y controversia que el car\u00e1cter del Quijote de Cervantes toma vida: un hombre que m\u00e1s all\u00e1 de la realidad, busca el amor y la justicia. Este car\u00e1cter se refleja en cierto modo en la propia vida de Strauss como compositor, sumergido en su propio mundo musical buscando las m\u00e1s sublimes metas art\u00edsticas.<\/p>\n<p><strong><u>BIBLIOGRAF\u00cdA CONSULTADA<\/u><\/strong><\/p>\n<p>Norman del Mar: <u>Richard Strauss: <em>Un comentario cr\u00edtico sobre su vida y obra<\/em><\/u>. Prensa de la Universidad de Cornell. 1986.<\/p>\n<p>Eduard Hanslick: <em>Los a\u00f1os dorados de la m\u00fasica en Viena 1850-1900<\/em>. Nueva York, Simon &amp; Schuster.1950<\/p>\n<p><em><u>El Nuevo Diccionario Grove de M\u00fasica y M\u00fasicos<\/u><\/em>. Revisado por Stanley Sadie. Londres MacMillan Editores.1980<\/p>\n<p>Comentarios del la grabaci\u00f3n Cl\u00e1sicos AB-67023, ABC Records, por Donald Johns.<\/p>\n<p>Mueller von Asow: Richard Strauss. <em><u>Descripci\u00f3n Tem\u00e1tica<\/u><\/em>. Editora L. Doblinger, Viena -Wisbaden. 1955<\/p>\n<p><u>Richard Strauss y Romaine Rolland Correspondencia<\/u>. Prensa de La Universidad de\u00a0 California, Berkley. LA. 1968<\/p>\n<p>Ernst Krause: Richard Strauss. <em><u>El Hombre y su Obra<\/u><\/em>. Collet\u2019s LTD. Londres. 1964.<\/p>\n<p>La Tribuna de Chicago. 8 de enero de 1899<\/p>\n<p>El Times de Nueva York. El 14 y 19 de febrero y el 4 de marzo de 1904.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Norman del Mar: <u>Ricardo Strauss: <em>Comentario Cr\u00edtico sobre su vida y obra<\/em><\/u>. Prensa de la Universidad de Cornell, 1986. P\u00e1g. 163.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Strauss se encontraba en Espa\u00f1a para el momento de la primera presentaci\u00f3n (8 de marzo de 1898). \u00c9sta fue conducida por Franz Wullner con Friederick Grutzmacher como el solista al chelo.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> La primera ejecuci\u00f3n norteamericana tuvo lugar en Chicago el 6 de enero de 1989, con la Orquesta Sinf\u00f3nica de Chicago bajo la direcci\u00f3n de Theodore Thomas, a menos de un a\u00f1o de la premi\u00e8re alemana.<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Correspondencia entre R. Rolland (1863-1941) y el franc\u00e9s Paul Tortelier (1914-90).<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Este rol no solamente es tomado por el solo de la viola, sino que en algunos episodios tambi\u00e9n es adoptado por la tuba tenor y el clarinete bajo.<\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> El Re grave en los bajos y t\u00edmpani describe, en realidad, que nunca levantaron vuelo (Cap\u00edtulo XLI).<\/p>\n<p><sup>7 <\/sup>Esto lo declara Hanslick despu\u00e9s de o\u00edr <em>Todd und Verkl\u00e4rung <\/em>en 1893.<\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\"><\/a><sup>8 <\/sup>Edward Hanslick: <em>Los a\u00f1os dorados de la m\u00fasica en Viena 1850-1900<\/em>. Nueva York, Simon &amp; Schuster 1950.<\/p>\n<p><sup>9 <\/sup>Carta de Rimsky a Taneyev. De los comentarios sobre grabaci\u00f3n <em>Classics AB-67023<\/em>, <em>ABC<\/em> Records, por Donald Johns.<\/p>\n<p><sup>10 <\/sup>Despu\u00e9s de escuchar <em>Don Quijote<\/em>, Dvorak describi\u00f3 con este t\u00e9rmino los requerimientos de cualquier composici\u00f3n orquestal. Ernst Krause: Ricardo Strauss. <em>El hombre y su obra<\/em>. Collet\u2019s Ltd. Londres, 1964; P\u00e1g. 170.<\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\"><\/a><sup>11 <\/sup>Ernst Krause: Ricardo Strauss. <em>El hombre y su obra<\/em>. Collet\u2019s Ltd. Londres, 1964; P\u00e1g. 223.<\/p>\n<p><a href=\"#_ftnref9\" name=\"_ftn9\"><\/a><\/p>\n<p><a href=\"#_ftnref10\" name=\"_ftn10\"><\/a><\/p>\n<p><a href=\"#_ftnref11\" name=\"_ftn11\"><\/a><\/p>\n<p><a href=\"#_ftnref12\" name=\"_ftn12\">[12]<\/a> Mueller von Asow: Richard Strauss. <em>Descripci\u00f3n Tem\u00e1tica<\/em>. Editora L. Doblinger. Viena-Wisbaden, 1955. Originalmente en Alem\u00e1n. P\u00e1g. 220.<\/p>\n<p><a href=\"#_ftnref13\" name=\"_ftn13\">[13]<\/a> Mueller von Asow: Richard Strauss. <em>Descripci\u00f3n Tem\u00e1tica<\/em>. Editora L. Doblinger. Viena-Wisbaden, 1955. Originalmente en Alem\u00e1n. P\u00e1g. 221.<\/p>\n<p style=\"text-align: center;\">\n<\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full-width.php","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-5397","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/germanmarcano.com\/germansite\/en\/wp-json\/wp\/v2\/pages\/5397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/germanmarcano.com\/germansite\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/germanmarcano.com\/germansite\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/germanmarcano.com\/germansite\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/germanmarcano.com\/germansite\/en\/wp-json\/wp\/v2\/comments?post=5397"}],"version-history":[{"count":5,"href":"https:\/\/germanmarcano.com\/germansite\/en\/wp-json\/wp\/v2\/pages\/5397\/revisions"}],"predecessor-version":[{"id":5409,"href":"https:\/\/germanmarcano.com\/germansite\/en\/wp-json\/wp\/v2\/pages\/5397\/revisions\/5409"}],"wp:attachment":[{"href":"https:\/\/germanmarcano.com\/germansite\/en\/wp-json\/wp\/v2\/media?parent=5397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}